{"id":18872,"date":"2014-10-30T11:00:24","date_gmt":"2014-10-30T11:00:24","guid":{"rendered":"https:\/\/ivir.sjef.nu\/publications\/de-noodzaak-om-privacy-als-publiek-belang-te-herfomuleren\/"},"modified":"2014-10-30T11:00:24","modified_gmt":"2014-10-30T11:00:24","slug":"de-noodzaak-om-privacy-als-publiek-belang-te-herfomuleren","status":"publish","type":"publications","link":"https:\/\/www.ivir.nl\/nl\/publications\/de-noodzaak-om-privacy-als-publiek-belang-te-herfomuleren\/","title":{"rendered":"De noodzaak om privacy als publiek belang te herfomuleren"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"template":"","authors":[2360],"keywords":[92,93],"types":[1357],"class_list":["post-18872","publications","type-publications","status-publish","hentry","authors-van-der-sloot-b","keywords-grondrechten","keywords-privacy","types-article","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>De noodzaak om privacy als publiek belang te herfomuleren - IVIR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ivir.nl\/publications\/de-noodzaak-om-privacy-als-publiek-belang-te-herfomuleren\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De noodzaak om privacy als publiek belang te herfomuleren - IVIR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ivir.nl\/publications\/de-noodzaak-om-privacy-als-publiek-belang-te-herfomuleren\/\" \/>\n<meta property=\"og:site_name\" content=\"IVIR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ivir_uva\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ivir.nl\\\/publications\\\/de-noodzaak-om-privacy-als-publiek-belang-te-herfomuleren\\\/\",\"url\":\"https:\\\/\\\/www.ivir.nl\\\/publications\\\/de-noodzaak-om-privacy-als-publiek-belang-te-herfomuleren\\\/\",\"name\":\"De noodzaak om privacy als publiek belang te herfomuleren - IVIR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ivir.nl\\\/#website\"},\"datePublished\":\"2014-10-30T11:00:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ivir.nl\\\/publications\\\/de-noodzaak-om-privacy-als-publiek-belang-te-herfomuleren\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ivir.nl\\\/publications\\\/de-noodzaak-om-privacy-als-publiek-belang-te-herfomuleren\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ivir.nl\\\/publications\\\/de-noodzaak-om-privacy-als-publiek-belang-te-herfomuleren\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ivir.nl\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Publications\",\"item\":\"https:\\\/\\\/www.ivir.nl\\\/publications\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"De noodzaak om privacy als publiek belang te herfomuleren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ivir.nl\\\/#website\",\"url\":\"https:\\\/\\\/www.ivir.nl\\\/\",\"name\":\"IVIR\",\"description\":\"Universiteit van Amsterdam\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ivir.nl\\\/#organization\"},\"alternateName\":\"Institute for Information Law\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ivir.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ivir.nl\\\/#organization\",\"name\":\"Institute for Information Law\",\"alternateName\":\"IVIR\",\"url\":\"https:\\\/\\\/www.ivir.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.ivir.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ivir.nl\\\/publicaties\\\/download\\\/IVIR_2023_LOGO-hoog.svg\",\"contentUrl\":\"https:\\\/\\\/www.ivir.nl\\\/publicaties\\\/download\\\/IVIR_2023_LOGO-hoog.svg\",\"width\":1,\"height\":1,\"caption\":\"Institute for Information Law\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ivir.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/ivir_uva\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/institute-for-information-law-ivir-\\\/\",\"https:\\\/\\\/bsky.app\\\/profile\\\/ivir-uva.bsky.social\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De noodzaak om privacy als publiek belang te herfomuleren - IVIR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ivir.nl\/publications\/de-noodzaak-om-privacy-als-publiek-belang-te-herfomuleren\/","og_locale":"nl_NL","og_type":"article","og_title":"De noodzaak om privacy als publiek belang te herfomuleren - IVIR","og_url":"https:\/\/www.ivir.nl\/publications\/de-noodzaak-om-privacy-als-publiek-belang-te-herfomuleren\/","og_site_name":"IVIR","twitter_card":"summary_large_image","twitter_site":"@ivir_uva","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ivir.nl\/publications\/de-noodzaak-om-privacy-als-publiek-belang-te-herfomuleren\/","url":"https:\/\/www.ivir.nl\/publications\/de-noodzaak-om-privacy-als-publiek-belang-te-herfomuleren\/","name":"De noodzaak om privacy als publiek belang te herfomuleren - IVIR","isPartOf":{"@id":"https:\/\/www.ivir.nl\/#website"},"datePublished":"2014-10-30T11:00:24+00:00","breadcrumb":{"@id":"https:\/\/www.ivir.nl\/publications\/de-noodzaak-om-privacy-als-publiek-belang-te-herfomuleren\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ivir.nl\/publications\/de-noodzaak-om-privacy-als-publiek-belang-te-herfomuleren\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ivir.nl\/publications\/de-noodzaak-om-privacy-als-publiek-belang-te-herfomuleren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ivir.nl\/nl\/"},{"@type":"ListItem","position":2,"name":"Publications","item":"https:\/\/www.ivir.nl\/publications\/"},{"@type":"ListItem","position":3,"name":"De noodzaak om privacy als publiek belang te herfomuleren"}]},{"@type":"WebSite","@id":"https:\/\/www.ivir.nl\/#website","url":"https:\/\/www.ivir.nl\/","name":"IVIR","description":"Universiteit van Amsterdam","publisher":{"@id":"https:\/\/www.ivir.nl\/#organization"},"alternateName":"Institute for Information Law","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ivir.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.ivir.nl\/#organization","name":"Institute for Information Law","alternateName":"IVIR","url":"https:\/\/www.ivir.nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.ivir.nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.ivir.nl\/publicaties\/download\/IVIR_2023_LOGO-hoog.svg","contentUrl":"https:\/\/www.ivir.nl\/publicaties\/download\/IVIR_2023_LOGO-hoog.svg","width":1,"height":1,"caption":"Institute for Information Law"},"image":{"@id":"https:\/\/www.ivir.nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/ivir_uva","https:\/\/www.linkedin.com\/company\/institute-for-information-law-ivir-\/","https:\/\/bsky.app\/profile\/ivir-uva.bsky.social"]}]}},"_links":{"self":[{"href":"https:\/\/www.ivir.nl\/nl\/wp-json\/wp\/v2\/publications\/18872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ivir.nl\/nl\/wp-json\/wp\/v2\/publications"}],"about":[{"href":"https:\/\/www.ivir.nl\/nl\/wp-json\/wp\/v2\/types\/publications"}],"version-history":[{"count":0,"href":"https:\/\/www.ivir.nl\/nl\/wp-json\/wp\/v2\/publications\/18872\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ivir.nl\/nl\/wp-json\/wp\/v2\/media?parent=18872"}],"wp:term":[{"taxonomy":"authors","embeddable":true,"href":"https:\/\/www.ivir.nl\/nl\/wp-json\/wp\/v2\/authors?post=18872"},{"taxonomy":"keywords","embeddable":true,"href":"https:\/\/www.ivir.nl\/nl\/wp-json\/wp\/v2\/keywords?post=18872"},{"taxonomy":"types","embeddable":true,"href":"https:\/\/www.ivir.nl\/nl\/wp-json\/wp\/v2\/types?post=18872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}